{"id":18,"count":19,"description":"","link":"https:\/\/sendaarchitects.com\/en\/category\/architecture\/","name":"Architecture","slug":"architecture","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Architecture archivos - Senda Arquitectos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendaarchitects.com\/en\/category\/architecture\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Architecture archivos - Senda Arquitectos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendaarchitects.com\/en\/category\/architecture\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Arquitectos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/sendaarchitects.com\/en\/category\/architecture\/\",\"url\":\"https:\/\/sendaarchitects.com\/en\/category\/architecture\/\",\"name\":\"Architecture archivos - Senda Arquitectos\",\"isPartOf\":{\"@id\":\"https:\/\/sendaarchitects.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/sendaarchitects.com\/en\/category\/architecture\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sendaarchitects.com\/en\/category\/architecture\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sendaarchitects.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Architecture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sendaarchitects.com\/en\/#website\",\"url\":\"https:\/\/sendaarchitects.com\/en\/\",\"name\":\"Senda Arquitectos\",\"description\":\"Estudio de arquitectura en Marbella\",\"publisher\":{\"@id\":\"https:\/\/sendaarchitects.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sendaarchitects.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sendaarchitects.com\/en\/#organization\",\"name\":\"Senda Arquitectos\",\"url\":\"https:\/\/sendaarchitects.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sendaarchitects.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sendaarchitects.com\/wp-content\/uploads\/2025\/06\/logo-arquitectos-marbella-senda-gris.png\",\"contentUrl\":\"https:\/\/sendaarchitects.com\/wp-content\/uploads\/2025\/06\/logo-arquitectos-marbella-senda-gris.png\",\"width\":1887,\"height\":377,\"caption\":\"Senda Arquitectos\"},\"image\":{\"@id\":\"https:\/\/sendaarchitects.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Architecture archivos - Senda Arquitectos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendaarchitects.com\/en\/category\/architecture\/","og_locale":"en_US","og_type":"article","og_title":"Architecture archivos - Senda Arquitectos","og_url":"https:\/\/sendaarchitects.com\/en\/category\/architecture\/","og_site_name":"Senda Arquitectos","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sendaarchitects.com\/en\/category\/architecture\/","url":"https:\/\/sendaarchitects.com\/en\/category\/architecture\/","name":"Architecture archivos - Senda Arquitectos","isPartOf":{"@id":"https:\/\/sendaarchitects.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/sendaarchitects.com\/en\/category\/architecture\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sendaarchitects.com\/en\/category\/architecture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendaarchitects.com\/en\/"},{"@type":"ListItem","position":2,"name":"Architecture"}]},{"@type":"WebSite","@id":"https:\/\/sendaarchitects.com\/en\/#website","url":"https:\/\/sendaarchitects.com\/en\/","name":"Senda Arquitectos","description":"Estudio de arquitectura en Marbella","publisher":{"@id":"https:\/\/sendaarchitects.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendaarchitects.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sendaarchitects.com\/en\/#organization","name":"Senda Arquitectos","url":"https:\/\/sendaarchitects.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sendaarchitects.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sendaarchitects.com\/wp-content\/uploads\/2025\/06\/logo-arquitectos-marbella-senda-gris.png","contentUrl":"https:\/\/sendaarchitects.com\/wp-content\/uploads\/2025\/06\/logo-arquitectos-marbella-senda-gris.png","width":1887,"height":377,"caption":"Senda Arquitectos"},"image":{"@id":"https:\/\/sendaarchitects.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sendaarchitects.com\/en\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendaarchitects.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sendaarchitects.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sendaarchitects.com\/en\/wp-json\/wp\/v2\/posts?categories=18"},{"href":"https:\/\/sendaarchitects.com\/en\/wp-json\/wp\/v2\/proyecto?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}